{"id":6,"name":"Luis Guilherme Tenorio dos Santos","url":"","description":"","link":"https:\/\/omundodoseguro.com.br\/index.php\/author\/luis\/","slug":"luis","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/595ff21a752ff30afa61c833c984d427?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/595ff21a752ff30afa61c833c984d427?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/595ff21a752ff30afa61c833c984d427?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"collection":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/users"}]}}