{"id":15,"count":6,"description":"Explica\u00e7\u00e3o de alguns termos no ramo de seguros","link":"https:\/\/omundodoseguro.com.br\/index.php\/category\/o-que-significa\/","name":"O que significa?","slug":"o-que-significa","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/categories\/15"}],"collection":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/omundodoseguro.com.br\/index.php\/wp-json\/wp\/v2\/posts?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}